{"id":18969,"date":"2025-12-21T11:36:46","date_gmt":"2025-12-21T10:36:46","guid":{"rendered":"https:\/\/ewb.lu\/?post_type=event&#038;p=18969"},"modified":"2025-12-21T12:17:59","modified_gmt":"2025-12-21T11:17:59","slug":"kinozauber-rio-ein-papagei-auf-abenteuer","status":"publish","type":"event","link":"https:\/\/ewb.lu\/en\/event\/kinozauber-rio-ein-papagei-auf-abenteuer\/","title":{"rendered":"Kinozauber: Rio- ein Papagei auf Abenteuer"},"content":{"rendered":"<section class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]<\/p>\n<p style=\"font-weight: 400;\">Et ass Fuesend! Wir schauen gemeinsam den Film \u201cRio\u201d. Auch in Rio wird Karneval gefeiert. Doch bevor der Film startet, wird sich erst einmal gest\u00e4rkt. Die Veranstaltung endet in einem kleinen Filmgespr\u00e4ch.<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_text_separator title=&#8221;Zum Inhalt des Films:&#8221; color=&#8221;purple&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<p style=\"font-weight: 400;\">Dem <strong>Papagei \u201cBlu\u201d<\/strong> geht es richtig gut. Zwar lebt er nicht in freier Wildbahn aber das M\u00e4dchen Linda hegt, pflegt und liebt ihn hei\u00df und innig. Blu f\u00fchrt \u00fcber Jahre hinweg ein \u201egl\u00fcckliches\u201c K\u00e4figvogelleben: <strong>Er bohrt im Schnabel, kann nicht fliegen, pinkelt auch mal ins Vogelbad und liebt Marshmallow-Kakao.<\/strong> Doch dann erfahren Blu und Linda, dass der Ara das einzige lebende M\u00e4nnchen seiner Art ist. Auf geht\u00b4s nach Rio, wo seine seltenen Artgenossen leben.<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/section>","protected":false},"excerpt":{"rendered":"<p>Filmnachmittag f\u00fcr Familien<\/p>\n","protected":false},"featured_media":17048,"template":"","program":[36,72],"class_list":["post-18969","event","type-event","status-publish","has-post-thumbnail","hentry","program-growing-together","program-literatur-und-film"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kinozauber: Rio- ein Papagei auf Abenteuer - EWB<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ewb.lu\/en\/event\/kinozauber-rio-ein-papagei-auf-abenteuer\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kinozauber: Rio- ein Papagei auf Abenteuer - EWB\" \/>\n<meta property=\"og:description\" content=\"Filmnachmittag f\u00fcr Familien\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ewb.lu\/en\/event\/kinozauber-rio-ein-papagei-auf-abenteuer\/\" \/>\n<meta property=\"og:site_name\" content=\"EWB\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ErwuesseBild\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-21T11:17:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ewb.lu\/wp-content\/uploads\/2025\/07\/Naechste-Woche-starten-unsere-Kamishibai-im-Park-Facebook-Post.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"940\" \/>\n\t<meta property=\"og:image:height\" content=\"788\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ewb.lu\\\/en\\\/event\\\/kinozauber-rio-ein-papagei-auf-abenteuer\\\/\",\"url\":\"https:\\\/\\\/ewb.lu\\\/en\\\/event\\\/kinozauber-rio-ein-papagei-auf-abenteuer\\\/\",\"name\":\"Kinozauber: Rio- ein Papagei auf Abenteuer - EWB\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ewb.lu\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ewb.lu\\\/en\\\/event\\\/kinozauber-rio-ein-papagei-auf-abenteuer\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ewb.lu\\\/en\\\/event\\\/kinozauber-rio-ein-papagei-auf-abenteuer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ewb.lu\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Naechste-Woche-starten-unsere-Kamishibai-im-Park-Facebook-Post.jpg\",\"datePublished\":\"2025-12-21T10:36:46+00:00\",\"dateModified\":\"2025-12-21T11:17:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ewb.lu\\\/en\\\/event\\\/kinozauber-rio-ein-papagei-auf-abenteuer\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ewb.lu\\\/en\\\/event\\\/kinozauber-rio-ein-papagei-auf-abenteuer\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ewb.lu\\\/en\\\/event\\\/kinozauber-rio-ein-papagei-auf-abenteuer\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ewb.lu\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Naechste-Woche-starten-unsere-Kamishibai-im-Park-Facebook-Post.jpg\",\"contentUrl\":\"https:\\\/\\\/ewb.lu\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Naechste-Woche-starten-unsere-Kamishibai-im-Park-Facebook-Post.jpg\",\"width\":940,\"height\":788},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ewb.lu\\\/en\\\/event\\\/kinozauber-rio-ein-papagei-auf-abenteuer\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/ewb.lu\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kinozauber: Rio- ein Papagei auf Abenteuer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ewb.lu\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ewb.lu\\\/en\\\/\",\"name\":\"EwB ErwuesseBildung\",\"description\":\"ErwuesseBildung\",\"publisher\":{\"@id\":\"https:\\\/\\\/ewb.lu\\\/en\\\/#organization\"},\"alternateName\":\"EWB\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ewb.lu\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ewb.lu\\\/en\\\/#organization\",\"name\":\"ErwuesseBildung Asbl\",\"alternateName\":\"EWB\",\"url\":\"https:\\\/\\\/ewb.lu\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ewb.lu\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ewb.lu\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/ewb-logo-header.svg\",\"contentUrl\":\"https:\\\/\\\/ewb.lu\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/ewb-logo-header.svg\",\"width\":301,\"height\":38,\"caption\":\"ErwuesseBildung Asbl\"},\"image\":{\"@id\":\"https:\\\/\\\/ewb.lu\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ErwuesseBild\\\/\",\"https:\\\/\\\/lu.linkedin.com\\\/company\\\/erwuessebildung---formation-dadultes\",\"https:\\\/\\\/www.instagram.com\\\/erwuessebildung_asbl\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kinozauber: Rio- ein Papagei auf Abenteuer - EWB","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ewb.lu\/en\/event\/kinozauber-rio-ein-papagei-auf-abenteuer\/","og_locale":"en_US","og_type":"article","og_title":"Kinozauber: Rio- ein Papagei auf Abenteuer - EWB","og_description":"Filmnachmittag f\u00fcr Familien","og_url":"https:\/\/ewb.lu\/en\/event\/kinozauber-rio-ein-papagei-auf-abenteuer\/","og_site_name":"EWB","article_publisher":"https:\/\/www.facebook.com\/ErwuesseBild\/","article_modified_time":"2025-12-21T11:17:59+00:00","og_image":[{"width":940,"height":788,"url":"https:\/\/ewb.lu\/wp-content\/uploads\/2025\/07\/Naechste-Woche-starten-unsere-Kamishibai-im-Park-Facebook-Post.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ewb.lu\/en\/event\/kinozauber-rio-ein-papagei-auf-abenteuer\/","url":"https:\/\/ewb.lu\/en\/event\/kinozauber-rio-ein-papagei-auf-abenteuer\/","name":"Kinozauber: Rio- ein Papagei auf Abenteuer - EWB","isPartOf":{"@id":"https:\/\/ewb.lu\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ewb.lu\/en\/event\/kinozauber-rio-ein-papagei-auf-abenteuer\/#primaryimage"},"image":{"@id":"https:\/\/ewb.lu\/en\/event\/kinozauber-rio-ein-papagei-auf-abenteuer\/#primaryimage"},"thumbnailUrl":"https:\/\/ewb.lu\/wp-content\/uploads\/2025\/07\/Naechste-Woche-starten-unsere-Kamishibai-im-Park-Facebook-Post.jpg","datePublished":"2025-12-21T10:36:46+00:00","dateModified":"2025-12-21T11:17:59+00:00","breadcrumb":{"@id":"https:\/\/ewb.lu\/en\/event\/kinozauber-rio-ein-papagei-auf-abenteuer\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ewb.lu\/en\/event\/kinozauber-rio-ein-papagei-auf-abenteuer\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ewb.lu\/en\/event\/kinozauber-rio-ein-papagei-auf-abenteuer\/#primaryimage","url":"https:\/\/ewb.lu\/wp-content\/uploads\/2025\/07\/Naechste-Woche-starten-unsere-Kamishibai-im-Park-Facebook-Post.jpg","contentUrl":"https:\/\/ewb.lu\/wp-content\/uploads\/2025\/07\/Naechste-Woche-starten-unsere-Kamishibai-im-Park-Facebook-Post.jpg","width":940,"height":788},{"@type":"BreadcrumbList","@id":"https:\/\/ewb.lu\/en\/event\/kinozauber-rio-ein-papagei-auf-abenteuer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/ewb.lu\/en\/"},{"@type":"ListItem","position":2,"name":"Kinozauber: Rio- ein Papagei auf Abenteuer"}]},{"@type":"WebSite","@id":"https:\/\/ewb.lu\/en\/#website","url":"https:\/\/ewb.lu\/en\/","name":"EwB ErwuesseBildung","description":"ErwuesseBildung","publisher":{"@id":"https:\/\/ewb.lu\/en\/#organization"},"alternateName":"EWB","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ewb.lu\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/ewb.lu\/en\/#organization","name":"ErwuesseBildung Asbl","alternateName":"EWB","url":"https:\/\/ewb.lu\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ewb.lu\/en\/#\/schema\/logo\/image\/","url":"https:\/\/ewb.lu\/wp-content\/uploads\/2022\/11\/ewb-logo-header.svg","contentUrl":"https:\/\/ewb.lu\/wp-content\/uploads\/2022\/11\/ewb-logo-header.svg","width":301,"height":38,"caption":"ErwuesseBildung Asbl"},"image":{"@id":"https:\/\/ewb.lu\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ErwuesseBild\/","https:\/\/lu.linkedin.com\/company\/erwuessebildung---formation-dadultes","https:\/\/www.instagram.com\/erwuessebildung_asbl\/"]}]}},"_links":{"self":[{"href":"https:\/\/ewb.lu\/en\/wp-json\/wp\/v2\/event\/18969","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ewb.lu\/en\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/ewb.lu\/en\/wp-json\/wp\/v2\/types\/event"}],"version-history":[{"count":3,"href":"https:\/\/ewb.lu\/en\/wp-json\/wp\/v2\/event\/18969\/revisions"}],"predecessor-version":[{"id":18984,"href":"https:\/\/ewb.lu\/en\/wp-json\/wp\/v2\/event\/18969\/revisions\/18984"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ewb.lu\/en\/wp-json\/wp\/v2\/media\/17048"}],"wp:attachment":[{"href":"https:\/\/ewb.lu\/en\/wp-json\/wp\/v2\/media?parent=18969"}],"wp:term":[{"taxonomy":"program","embeddable":true,"href":"https:\/\/ewb.lu\/en\/wp-json\/wp\/v2\/program?post=18969"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}