{"id":18251,"date":"2025-11-20T12:48:21","date_gmt":"2025-11-20T11:48:21","guid":{"rendered":"https:\/\/ewb.lu\/?post_type=event&#038;p=18251"},"modified":"2026-01-19T10:10:30","modified_gmt":"2026-01-19T09:10:30","slug":"krixkrax-ausstellung-liesung-mam-marc-weydert","status":"publish","type":"event","link":"https:\/\/ewb.lu\/fr\/event\/krixkrax-ausstellung-liesung-mam-marc-weydert\/","title":{"rendered":"Krixkrax: Liesung mam Marc Weydert"},"content":{"rendered":"<section class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]<\/p>\n<div>\n<h4><strong><em><span lang=\"DE-CH\" style=\"color: #f47f57;\">Gew\u00ebnner vum L\u00ebtzebuerger Buchpr\u00e4is &amp; Publikumspr\u00e4is an der Kategorie \u00ab\u00a0Kannerbuch\u00a0\u00bb <\/span><\/em><\/strong><\/h4>\n<\/div>\n<p style=\"font-weight: 400;\">Den 11. Januar liest den Auteur <strong>Marc Weydert <\/strong>aus sengem Billerbuch <em><strong>Krixkrax<\/strong><\/em> vir.<\/p>\n<p style=\"font-weight: 400;\">De Kinnek huet eng lusch Krankheet, iwwerall op sengem Kierper tauche faarweg T\u00ebppelen op!\u00a0 Keen weess sech ee Rot. Aus dem Grond w\u00ebllen se d\u2019Hex Krixkrax em Rot froen. Mee d\u00e9i s\u00ebtzt uewen an hirem Tuerm, ganz ofgeschott vun all deenen aneren an d&rsquo;Bewunner vum Kinnekr\u00e4ich versiche mat deene verschiddensten Iddie bei si erop ze kommen. Schlussendlech f\u00ebnnt ee Kand eng ganz effektiv, wei och einfach L\u00e9isung. Mee m\u00e9i soll net verrode ginn.<\/p>\n<p style=\"font-weight: 400;\">Krixkrax huet am November de <strong>L\u00ebtzebuerg Buchpr\u00e4is 2025 am Ber\u00e4ich Kanner- a Jugendbuch<\/strong>, esou ew\u00e9i de <strong>Publikumspr\u00e4is<\/strong> gewonnen an iwwerzeegt mat sengen ureegende Reimen an detailr\u00e4iche Biller, d\u00e9i hier ganz eege Geschicht erzielen.<\/p>\n<p style=\"font-weight: 400;\"><strong>D\u2019Biller vun d\u00ebsem Buch sinn an der EwB vum 10. Januar \u2013 24. Januar ausgestallt. \u00cbffnungsz\u00e4iten: M\u00e9-Do, 10-12 Auer &amp; 14-16 Auer<\/strong><\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=\u00a0\u00bb1\/2&Prime;][vc_single_image image=\u00a0\u00bb18352&Prime; img_size=\u00a0\u00bblarge\u00a0\u00bb][\/vc_column][vc_column width=\u00a0\u00bb1\/2&Prime;][vc_single_image image=\u00a0\u00bb18355&Prime; img_size=\u00a0\u00bblarge\u00a0\u00bb][\/vc_column][\/vc_row][vc_row][vc_column][vc_text_separator title=\u00a0\u00bbRahmenprogramm\u00a0\u00bb color=\u00a0\u00bbpurple\u00a0\u00bb][\/vc_column][\/vc_row][vc_row][vc_column width=\u00a0\u00bb1\/4&Prime;][\/vc_column][vc_column width=\u00a0\u00bb1\/2&Prime;][vc_column_text]<\/p>\n<ul>\n<li><a href=\"https:\/\/ewb.lu\/event\/krixkrax-ausstellung-billerbuchsaeit-molen\/\">Billerbuchs\u00e4it molen<\/a><\/li>\n<li><a href=\"https:\/\/ewb.lu\/event\/schreifworkshop-maerecher\/\">Schreifworkshop: M\u00e4rercher<\/a><\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column][vc_column width=\u00a0\u00bb1\/4&Prime;][\/vc_column][\/vc_row][vc_row][vc_column][vc_separator color=\u00a0\u00bbpurple\u00a0\u00bb][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<a href=\"https:\/\/ewb.lu\/event\/krixkrax-ausstellung-zum-buch\/\">Infoen iwwert d&rsquo;Ausstellung fannt Dir hei (op den Text klicken).<\/a>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/section>","protected":false},"excerpt":{"rendered":"<p>Gew\u00ebnner vum L\u00ebtzebuerger Buchpr\u00e4is &#038; Publikumspr\u00e4is (Kannerbuch)<\/p>\n","protected":false},"featured_media":18252,"template":"","program":[36,72],"class_list":["post-18251","event","type-event","status-publish","has-post-thumbnail","hentry","program-growing-together","program-literatur-und-film"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Krixkrax: Liesung mam Marc Weydert - EWB<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ewb.lu\/fr\/event\/krixkrax-ausstellung-liesung-mam-marc-weydert\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Krixkrax: Liesung mam Marc Weydert - EWB\" \/>\n<meta property=\"og:description\" content=\"Gew\u00ebnner vum L\u00ebtzebuerger Buchpr\u00e4is &amp; Publikumspr\u00e4is (Kannerbuch)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ewb.lu\/fr\/event\/krixkrax-ausstellung-liesung-mam-marc-weydert\/\" \/>\n<meta property=\"og:site_name\" content=\"EWB\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ErwuesseBild\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-19T09:10:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ewb.lu\/wp-content\/uploads\/2025\/11\/Krixkrax.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"908\" \/>\n\t<meta property=\"og:image:height\" content=\"1164\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ewb.lu\\\/fr\\\/event\\\/krixkrax-ausstellung-liesung-mam-marc-weydert\\\/\",\"url\":\"https:\\\/\\\/ewb.lu\\\/fr\\\/event\\\/krixkrax-ausstellung-liesung-mam-marc-weydert\\\/\",\"name\":\"Krixkrax: Liesung mam Marc Weydert - EWB\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ewb.lu\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ewb.lu\\\/fr\\\/event\\\/krixkrax-ausstellung-liesung-mam-marc-weydert\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ewb.lu\\\/fr\\\/event\\\/krixkrax-ausstellung-liesung-mam-marc-weydert\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ewb.lu\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Krixkrax.jpg\",\"datePublished\":\"2025-11-20T11:48:21+00:00\",\"dateModified\":\"2026-01-19T09:10:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ewb.lu\\\/fr\\\/event\\\/krixkrax-ausstellung-liesung-mam-marc-weydert\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ewb.lu\\\/fr\\\/event\\\/krixkrax-ausstellung-liesung-mam-marc-weydert\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/ewb.lu\\\/fr\\\/event\\\/krixkrax-ausstellung-liesung-mam-marc-weydert\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ewb.lu\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Krixkrax.jpg\",\"contentUrl\":\"https:\\\/\\\/ewb.lu\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Krixkrax.jpg\",\"width\":908,\"height\":1164},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ewb.lu\\\/fr\\\/event\\\/krixkrax-ausstellung-liesung-mam-marc-weydert\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/ewb.lu\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Krixkrax: Liesung mam Marc Weydert\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ewb.lu\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/ewb.lu\\\/fr\\\/\",\"name\":\"EwB ErwuesseBildung\",\"description\":\"ErwuesseBildung\",\"publisher\":{\"@id\":\"https:\\\/\\\/ewb.lu\\\/fr\\\/#organization\"},\"alternateName\":\"EWB\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ewb.lu\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ewb.lu\\\/fr\\\/#organization\",\"name\":\"ErwuesseBildung Asbl\",\"alternateName\":\"EWB\",\"url\":\"https:\\\/\\\/ewb.lu\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/ewb.lu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ewb.lu\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/ewb-logo-header.svg\",\"contentUrl\":\"https:\\\/\\\/ewb.lu\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/ewb-logo-header.svg\",\"width\":301,\"height\":38,\"caption\":\"ErwuesseBildung Asbl\"},\"image\":{\"@id\":\"https:\\\/\\\/ewb.lu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ErwuesseBild\\\/\",\"https:\\\/\\\/lu.linkedin.com\\\/company\\\/erwuessebildung---formation-dadultes\",\"https:\\\/\\\/www.instagram.com\\\/erwuessebildung_asbl\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Krixkrax: Liesung mam Marc Weydert - EWB","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ewb.lu\/fr\/event\/krixkrax-ausstellung-liesung-mam-marc-weydert\/","og_locale":"fr_FR","og_type":"article","og_title":"Krixkrax: Liesung mam Marc Weydert - EWB","og_description":"Gew\u00ebnner vum L\u00ebtzebuerger Buchpr\u00e4is & Publikumspr\u00e4is (Kannerbuch)","og_url":"https:\/\/ewb.lu\/fr\/event\/krixkrax-ausstellung-liesung-mam-marc-weydert\/","og_site_name":"EWB","article_publisher":"https:\/\/www.facebook.com\/ErwuesseBild\/","article_modified_time":"2026-01-19T09:10:30+00:00","og_image":[{"width":908,"height":1164,"url":"https:\/\/ewb.lu\/wp-content\/uploads\/2025\/11\/Krixkrax.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ewb.lu\/fr\/event\/krixkrax-ausstellung-liesung-mam-marc-weydert\/","url":"https:\/\/ewb.lu\/fr\/event\/krixkrax-ausstellung-liesung-mam-marc-weydert\/","name":"Krixkrax: Liesung mam Marc Weydert - EWB","isPartOf":{"@id":"https:\/\/ewb.lu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ewb.lu\/fr\/event\/krixkrax-ausstellung-liesung-mam-marc-weydert\/#primaryimage"},"image":{"@id":"https:\/\/ewb.lu\/fr\/event\/krixkrax-ausstellung-liesung-mam-marc-weydert\/#primaryimage"},"thumbnailUrl":"https:\/\/ewb.lu\/wp-content\/uploads\/2025\/11\/Krixkrax.jpg","datePublished":"2025-11-20T11:48:21+00:00","dateModified":"2026-01-19T09:10:30+00:00","breadcrumb":{"@id":"https:\/\/ewb.lu\/fr\/event\/krixkrax-ausstellung-liesung-mam-marc-weydert\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ewb.lu\/fr\/event\/krixkrax-ausstellung-liesung-mam-marc-weydert\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ewb.lu\/fr\/event\/krixkrax-ausstellung-liesung-mam-marc-weydert\/#primaryimage","url":"https:\/\/ewb.lu\/wp-content\/uploads\/2025\/11\/Krixkrax.jpg","contentUrl":"https:\/\/ewb.lu\/wp-content\/uploads\/2025\/11\/Krixkrax.jpg","width":908,"height":1164},{"@type":"BreadcrumbList","@id":"https:\/\/ewb.lu\/fr\/event\/krixkrax-ausstellung-liesung-mam-marc-weydert\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/ewb.lu\/fr\/"},{"@type":"ListItem","position":2,"name":"Krixkrax: Liesung mam Marc Weydert"}]},{"@type":"WebSite","@id":"https:\/\/ewb.lu\/fr\/#website","url":"https:\/\/ewb.lu\/fr\/","name":"EwB ErwuesseBildung","description":"ErwuesseBildung","publisher":{"@id":"https:\/\/ewb.lu\/fr\/#organization"},"alternateName":"EWB","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ewb.lu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/ewb.lu\/fr\/#organization","name":"ErwuesseBildung Asbl","alternateName":"EWB","url":"https:\/\/ewb.lu\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ewb.lu\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/ewb.lu\/wp-content\/uploads\/2022\/11\/ewb-logo-header.svg","contentUrl":"https:\/\/ewb.lu\/wp-content\/uploads\/2022\/11\/ewb-logo-header.svg","width":301,"height":38,"caption":"ErwuesseBildung Asbl"},"image":{"@id":"https:\/\/ewb.lu\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ErwuesseBild\/","https:\/\/lu.linkedin.com\/company\/erwuessebildung---formation-dadultes","https:\/\/www.instagram.com\/erwuessebildung_asbl\/"]}]}},"_links":{"self":[{"href":"https:\/\/ewb.lu\/fr\/wp-json\/wp\/v2\/event\/18251","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ewb.lu\/fr\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/ewb.lu\/fr\/wp-json\/wp\/v2\/types\/event"}],"version-history":[{"count":15,"href":"https:\/\/ewb.lu\/fr\/wp-json\/wp\/v2\/event\/18251\/revisions"}],"predecessor-version":[{"id":19338,"href":"https:\/\/ewb.lu\/fr\/wp-json\/wp\/v2\/event\/18251\/revisions\/19338"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ewb.lu\/fr\/wp-json\/wp\/v2\/media\/18252"}],"wp:attachment":[{"href":"https:\/\/ewb.lu\/fr\/wp-json\/wp\/v2\/media?parent=18251"}],"wp:term":[{"taxonomy":"program","embeddable":true,"href":"https:\/\/ewb.lu\/fr\/wp-json\/wp\/v2\/program?post=18251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}