{"id":18585,"date":"2025-12-04T15:33:16","date_gmt":"2025-12-04T14:33:16","guid":{"rendered":"https:\/\/ewb.lu\/?post_type=event&#038;p=18585"},"modified":"2026-04-27T09:12:38","modified_gmt":"2026-04-27T07:12:38","slug":"die-waldwichtel-14","status":"publish","type":"event","link":"https:\/\/ewb.lu\/fr\/event\/die-waldwichtel-14\/","title":{"rendered":"Die Waldwichtel"},"content":{"rendered":"<section class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]<\/p>\n<h3 style=\"font-weight: 400;\"><strong><span style=\"color: #f47f57;\"><em>Ausflug in den Wald<\/em><\/span><\/strong><\/h3>\n<p style=\"font-weight: 400;\">Eltern unternehmen mit ihren 2\u20134-j\u00e4hrigen Kindern einen Ausflug in den Wald. Hier k\u00f6nnen die Kinder <strong>Natur unmittelbar erleben und begreifen<\/strong>. Der Wald \u00e4ndert t\u00e4glich sein Gesicht. So erleben die Kinder den Lauf der Jahreszeiten.<\/p>\n<p style=\"font-weight: 400;\">Jeden Tag gibt es Neues zu entdecken: V\u00f6gel und K\u00e4fer, Bl\u00e4tter und \u00c4ste, Steine und Wasser, Ger\u00e4usche und Stille, Blumen und Beeren. Die Kinder erleben, ertasten, erfahren und erf\u00fchlen die Natur. <strong>Spiele, Lieder und viel Bewegung<\/strong> begleiten den Ausflug in den Wald.<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_text_separator title=\u00a0\u00bbBitte mitbringen:\u00a0\u00bb color=\u00a0\u00bbpurple\u00a0\u00bb][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]Wettergerechte Kleidung, von Kopf bis Fu\u00df![\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/section>","protected":false},"excerpt":{"rendered":"<p>Natur erleben und begreifen<\/p>\n","protected":false},"featured_media":18369,"template":"","program":[36,204],"class_list":["post-18585","event","type-event","status-publish","has-post-thumbnail","hentry","program-growing-together","program-natur"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Die Waldwichtel - EWB<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ewb.lu\/fr\/event\/die-waldwichtel-14\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die Waldwichtel - EWB\" \/>\n<meta property=\"og:description\" content=\"Natur erleben und begreifen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ewb.lu\/fr\/event\/die-waldwichtel-14\/\" \/>\n<meta property=\"og:site_name\" content=\"EWB\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ErwuesseBild\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-27T07:12:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ewb.lu\/wp-content\/uploads\/2025\/11\/SPC_FB-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"2146\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ewb.lu\\\/fr\\\/event\\\/die-waldwichtel-14\\\/\",\"url\":\"https:\\\/\\\/ewb.lu\\\/fr\\\/event\\\/die-waldwichtel-14\\\/\",\"name\":\"Die Waldwichtel - EWB\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ewb.lu\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ewb.lu\\\/fr\\\/event\\\/die-waldwichtel-14\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ewb.lu\\\/fr\\\/event\\\/die-waldwichtel-14\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ewb.lu\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/SPC_FB-2.jpg\",\"datePublished\":\"2025-12-04T14:33:16+00:00\",\"dateModified\":\"2026-04-27T07:12:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ewb.lu\\\/fr\\\/event\\\/die-waldwichtel-14\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ewb.lu\\\/fr\\\/event\\\/die-waldwichtel-14\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/ewb.lu\\\/fr\\\/event\\\/die-waldwichtel-14\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ewb.lu\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/SPC_FB-2.jpg\",\"contentUrl\":\"https:\\\/\\\/ewb.lu\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/SPC_FB-2.jpg\",\"width\":2560,\"height\":2146},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ewb.lu\\\/fr\\\/event\\\/die-waldwichtel-14\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/ewb.lu\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Die Waldwichtel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ewb.lu\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/ewb.lu\\\/fr\\\/\",\"name\":\"EwB ErwuesseBildung\",\"description\":\"ErwuesseBildung\",\"publisher\":{\"@id\":\"https:\\\/\\\/ewb.lu\\\/fr\\\/#organization\"},\"alternateName\":\"EWB\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ewb.lu\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ewb.lu\\\/fr\\\/#organization\",\"name\":\"ErwuesseBildung Asbl\",\"alternateName\":\"EWB\",\"url\":\"https:\\\/\\\/ewb.lu\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/ewb.lu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ewb.lu\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/ewb-logo-header.svg\",\"contentUrl\":\"https:\\\/\\\/ewb.lu\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/ewb-logo-header.svg\",\"width\":301,\"height\":38,\"caption\":\"ErwuesseBildung Asbl\"},\"image\":{\"@id\":\"https:\\\/\\\/ewb.lu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ErwuesseBild\\\/\",\"https:\\\/\\\/lu.linkedin.com\\\/company\\\/erwuessebildung---formation-dadultes\",\"https:\\\/\\\/www.instagram.com\\\/erwuessebildung_asbl\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Die Waldwichtel - EWB","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ewb.lu\/fr\/event\/die-waldwichtel-14\/","og_locale":"fr_FR","og_type":"article","og_title":"Die Waldwichtel - EWB","og_description":"Natur erleben und begreifen","og_url":"https:\/\/ewb.lu\/fr\/event\/die-waldwichtel-14\/","og_site_name":"EWB","article_publisher":"https:\/\/www.facebook.com\/ErwuesseBild\/","article_modified_time":"2026-04-27T07:12:38+00:00","og_image":[{"width":2560,"height":2146,"url":"https:\/\/ewb.lu\/wp-content\/uploads\/2025\/11\/SPC_FB-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ewb.lu\/fr\/event\/die-waldwichtel-14\/","url":"https:\/\/ewb.lu\/fr\/event\/die-waldwichtel-14\/","name":"Die Waldwichtel - EWB","isPartOf":{"@id":"https:\/\/ewb.lu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ewb.lu\/fr\/event\/die-waldwichtel-14\/#primaryimage"},"image":{"@id":"https:\/\/ewb.lu\/fr\/event\/die-waldwichtel-14\/#primaryimage"},"thumbnailUrl":"https:\/\/ewb.lu\/wp-content\/uploads\/2025\/11\/SPC_FB-2.jpg","datePublished":"2025-12-04T14:33:16+00:00","dateModified":"2026-04-27T07:12:38+00:00","breadcrumb":{"@id":"https:\/\/ewb.lu\/fr\/event\/die-waldwichtel-14\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ewb.lu\/fr\/event\/die-waldwichtel-14\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ewb.lu\/fr\/event\/die-waldwichtel-14\/#primaryimage","url":"https:\/\/ewb.lu\/wp-content\/uploads\/2025\/11\/SPC_FB-2.jpg","contentUrl":"https:\/\/ewb.lu\/wp-content\/uploads\/2025\/11\/SPC_FB-2.jpg","width":2560,"height":2146},{"@type":"BreadcrumbList","@id":"https:\/\/ewb.lu\/fr\/event\/die-waldwichtel-14\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/ewb.lu\/fr\/"},{"@type":"ListItem","position":2,"name":"Die Waldwichtel"}]},{"@type":"WebSite","@id":"https:\/\/ewb.lu\/fr\/#website","url":"https:\/\/ewb.lu\/fr\/","name":"EwB ErwuesseBildung","description":"ErwuesseBildung","publisher":{"@id":"https:\/\/ewb.lu\/fr\/#organization"},"alternateName":"EWB","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ewb.lu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/ewb.lu\/fr\/#organization","name":"ErwuesseBildung Asbl","alternateName":"EWB","url":"https:\/\/ewb.lu\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ewb.lu\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/ewb.lu\/wp-content\/uploads\/2022\/11\/ewb-logo-header.svg","contentUrl":"https:\/\/ewb.lu\/wp-content\/uploads\/2022\/11\/ewb-logo-header.svg","width":301,"height":38,"caption":"ErwuesseBildung Asbl"},"image":{"@id":"https:\/\/ewb.lu\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ErwuesseBild\/","https:\/\/lu.linkedin.com\/company\/erwuessebildung---formation-dadultes","https:\/\/www.instagram.com\/erwuessebildung_asbl\/"]}]}},"_links":{"self":[{"href":"https:\/\/ewb.lu\/fr\/wp-json\/wp\/v2\/event\/18585","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ewb.lu\/fr\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/ewb.lu\/fr\/wp-json\/wp\/v2\/types\/event"}],"version-history":[{"count":3,"href":"https:\/\/ewb.lu\/fr\/wp-json\/wp\/v2\/event\/18585\/revisions"}],"predecessor-version":[{"id":20992,"href":"https:\/\/ewb.lu\/fr\/wp-json\/wp\/v2\/event\/18585\/revisions\/20992"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ewb.lu\/fr\/wp-json\/wp\/v2\/media\/18369"}],"wp:attachment":[{"href":"https:\/\/ewb.lu\/fr\/wp-json\/wp\/v2\/media?parent=18585"}],"wp:term":[{"taxonomy":"program","embeddable":true,"href":"https:\/\/ewb.lu\/fr\/wp-json\/wp\/v2\/program?post=18585"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}